{"id":10075,"date":"2022-03-31T09:59:50","date_gmt":"2022-03-31T12:59:50","guid":{"rendered":"https:\/\/polyexcel.com.br\/?p=10075"},"modified":"2022-04-01T10:03:49","modified_gmt":"2022-04-01T13:03:49","slug":"sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental","status":"publish","type":"post","link":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/","title":{"rendered":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hay varios procesos que suceden a nuestro alrededor, pero ni siquiera podemos imaginar. \u00bfHas o\u00eddo hablar de la <\/span><b>polimerizaci\u00f3n<\/b><span style=\"font-weight: 400;\">, por ejemplo? Esta reacci\u00f3n qu\u00edmica es la responsable de crear muchos de los objetos, materiales y compuestos con los que interactuamos en la vida diaria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, \u00bf<\/span><b>qu\u00e9 es la polimerizaci\u00f3n<\/b><span style=\"font-weight: 400;\"> y qu\u00e9 produce de tan importante? Si esa es tu pregunta, \u00a1est\u00e1s en el lugar correcto! En el siguiente contenido exclusivo, Polyexcel explicar\u00e1 todo sobre esta reacci\u00f3n y lo importante que es para la humanidad. \u00a1Sigue leyendo!<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es la polimerizaci\u00f3n?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En otro contenido que ya hemos tra\u00eddo a nuestro blog, explicamos en profundidad qu\u00e9 son los pol\u00edmeros. Simplemente, son macromol\u00e9culas formadas a partir de mol\u00e9culas peque\u00f1as, que llamamos mon\u00f3meros. De ah\u00ed viene el nombre de los <\/span><b>pol\u00edmeros<\/b><span style=\"font-weight: 400;\">: \u00abpoli\u00bb significa \u00abmuchos\u00bb, mientras que \u00abmeros\u00bb significa \u00abpartes\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, estas partes dependen de un proceso para unirse en una sola cosa. Esta es la <\/span><b>reacci\u00f3n de polimerizaci\u00f3n<\/b><span style=\"font-weight: 400;\">, que forma las macromol\u00e9culas que llamamos pol\u00edmeros de la uni\u00f3n de los mon\u00f3meros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este proceso es m\u00e1s com\u00fan de lo que piensas. Todo el tiempo y en todas partes, hay mol\u00e9culas que pasan a trav\u00e9s de \u00e9l. Esto se debe a que la polimerizaci\u00f3n es una reacci\u00f3n natural, y ejemplos de esto son el l\u00e1tex, la celulosa y el almid\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, existe una polimerizaci\u00f3n sint\u00e9tica que, a su vez, forma <\/span><a href=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/la-fabricacion-de-polimeros-y-la-industria-latinoamericana\/\"><span style=\"font-weight: 400;\">pol\u00edmeros<\/span><\/a><span style=\"font-weight: 400;\"> sint\u00e9ticos. Los compuestos resultantes de este proceso en el laboratorio tambi\u00e9n son bien conocidos por nosotros. Ejemplos de esto son el PVC, el polietileno y el poli\u00e9ster.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Tipos de polimerizaci\u00f3n<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Como explicamos anteriormente, hay dos tipos principales de polimerizaci\u00f3n: natural y sint\u00e9tica. Sin embargo, esta no es la \u00fanica forma de clasificar este tipo de reacci\u00f3n qu\u00edmica. Tanto los pol\u00edmeros naturales como los sint\u00e9ticos pueden ser el resultado de la polimerizaci\u00f3n por condensaci\u00f3n o la polimerizaci\u00f3n por adici\u00f3n.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Condensaci\u00f3n<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La<\/span><b> polimerizaci\u00f3n por condensaci\u00f3n<\/b><span style=\"font-weight: 400;\"> fue el primer tipo descubierto en 1909 por Leo Hendrik Baekeland, un qu\u00edmico belga. El invent\u00f3 la baquelita, el primer pol\u00edmero sint\u00e9tico de condensaci\u00f3n: una resina sint\u00e9tica formada a partir de la polimerizaci\u00f3n del fenol con metanal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los pol\u00edmeros de condensaci\u00f3n se forman en etapas. Es un proceso lento, ya que la uni\u00f3n de los mon\u00f3meros ocurre individualmente, de mol\u00e9cula en mol\u00e9cula, hasta llegar a un pol\u00edmero.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La principal caracter\u00edstica de este proceso es que, durante la reacci\u00f3n qu\u00edmica, se descarta una de las mol\u00e9culas de reacci\u00f3n, no estando presente en el pol\u00edmero final. Por lo tanto, sus resultados tambi\u00e9n se pueden llamar pol\u00edmeros de eliminaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de la propia baquelita, otros <\/span><a href=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/polimeros-de-condensacion-que-son-y-cual-es-su-importancia-en-nuestra-vida-diaria\/\"><span style=\"font-weight: 400;\">pol\u00edmeros de condensaci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\"> que utilizamos son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">poli\u00e9ster: utilizado en ropa, botellas, tapicer\u00eda, instrumentos musicales, etc;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">poliamida (nylon): presente en cepillos de dientes, tornillos, ropa, etc;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">silicona: se utiliza en implantes, art\u00edculos para el hogar, cosm\u00e9ticos, moldes, etc.<\/span><\/li>\n<\/ul>\n<h4><span style=\"font-weight: 400;\">Reestructuraci\u00f3n<\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Investigando este tema, se puede encontrar el t\u00e9rmino \u00abpol\u00edmeros de reestructuraci\u00f3n\u00bb. Este tipo de compuesto es el resultado de la polimerizaci\u00f3n por reestructuraci\u00f3n, un tipo de reacci\u00f3n de condensaci\u00f3n diferenciada. El poliuretano es uno de los pol\u00edmeros resultantes de \u00e9l.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Adici\u00f3n<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La <\/span><b>polimerizaci\u00f3n por adici\u00f3n<\/b><span style=\"font-weight: 400;\">, a su vez, ocurre a trav\u00e9s de la reacci\u00f3n en cadena, en la que debe haber la ruptura de los enlaces pi de los mon\u00f3meros. Cuando esto sucede, aparece una valencia libre de \u00e1tomos de carbono en cada mol\u00e9cula.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con esto, estas mol\u00e9culas pueden unirse entre s\u00ed, formando un pol\u00edmero. B\u00e1sicamente, hay tres procesos principales: iniciaci\u00f3n, propagaci\u00f3n y terminaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos ejemplos de pol\u00edmeros de adici\u00f3n que conocemos son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">polietileno: utilizado en pa\u00f1ales, biberones, envases, etc;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">polipropileno: utilizado en sillas de pl\u00e1stico, embalajes, telas, cajas, etc;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">PVC: presente en cables, zapatos, tuber\u00edas, cables, productos m\u00e9dico-hospitalarios, etc.\u00a0<\/span><\/li>\n<\/ul>\n<h2><span style=\"font-weight: 400;\">Grado de polimerizaci\u00f3n<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Otro t\u00e9rmino recurrente cuando hablamos de polimerizaci\u00f3n es el <\/span><b>grado de polimerizaci\u00f3n<\/b><span style=\"font-weight: 400;\">. Este es un concepto simple, que representa la cantidad de meros que componen un pol\u00edmero. Sin embargo, es muy importante para esta industria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El an\u00e1lisis del grado de polimerizaci\u00f3n de un pol\u00edmero determina varios factores fundamentales sobre el compuesto estudiado. El valor de un grado de polimerizaci\u00f3n puede variar dependiendo de la masa molar y la polidispersi\u00f3n de un compuesto polim\u00e9rico.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00a1Sigue aprendiendo de Polyexcel!<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00bfTe ha gustado saber un poco m\u00e1s sobre el universo de los pol\u00edmeros? \u00a1As\u00ed que disfruta de la visita y sigue aprendiendo del contenido que publicamos aqu\u00ed, en el blog de Polyexcel! Hay varios temas para que descubras a\u00fan m\u00e1s sobre estos compuestos tan importantes para nuestra vida diaria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Polyexcel produce compuestos polim\u00e9ricos de calidad para que aproveches al m\u00e1ximo su bienestar! Si quieres saber m\u00e1s sobre lo que hacemos, <\/span><a href=\"https:\/\/polyexcel.com.br\/es\/entre-en-contacto\/\"><span style=\"font-weight: 400;\">ponte en contacto<\/span><\/a><span style=\"font-weight: 400;\"> con nosotros. \u00a1Ser\u00e1 un placer presentarle nuestros productos!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay varios procesos que suceden a nuestro alrededor, pero ni siquiera podemos imaginar. \u00bfHas o\u00eddo hablar de la polimerizaci\u00f3n, por ejemplo? Esta reacci\u00f3n qu\u00edmica es la responsable de crear muchos de los objetos, materiales y compuestos con los que interactuamos en la vida diaria. Entonces, \u00bfqu\u00e9 es la polimerizaci\u00f3n y qu\u00e9 produce de tan importante? Si esa es tu pregunta, \u00a1est\u00e1s en el lugar correcto! En el siguiente contenido exclusivo, Polyexcel explicar\u00e1 todo sobre esta reacci\u00f3n y lo importante que es para la humanidad. \u00a1Sigue leyendo! \u00bfQu\u00e9 es la polimerizaci\u00f3n? En otro contenido que ya hemos tra\u00eddo a nuestro blog, explicamos en profundidad qu\u00e9 son los pol\u00edmeros. Simplemente, son macromol\u00e9culas formadas a partir de mol\u00e9culas peque\u00f1as, que llamamos mon\u00f3meros. De ah\u00ed viene el nombre de los pol\u00edmeros: \u00abpoli\u00bb significa \u00abmuchos\u00bb, mientras que \u00abmeros\u00bb significa \u00abpartes\u00bb. Sin embargo, estas partes dependen de un proceso para unirse en una sola cosa. Esta es la reacci\u00f3n de polimerizaci\u00f3n, que forma las macromol\u00e9culas que llamamos pol\u00edmeros de la uni\u00f3n de los mon\u00f3meros. Este proceso es m\u00e1s com\u00fan de lo que piensas. Todo el tiempo y en todas partes, hay mol\u00e9culas que pasan a trav\u00e9s de \u00e9l. Esto se debe a que la polimerizaci\u00f3n es una reacci\u00f3n natural, y ejemplos de esto son el l\u00e1tex, la celulosa y el almid\u00f3n. Adem\u00e1s, existe una polimerizaci\u00f3n sint\u00e9tica que, a su vez, forma pol\u00edmeros sint\u00e9ticos. Los compuestos resultantes de este proceso en el laboratorio tambi\u00e9n son bien conocidos por nosotros. Ejemplos de esto son el PVC, el polietileno y el poli\u00e9ster.\u00a0 Tipos de polimerizaci\u00f3n Como explicamos anteriormente, hay dos tipos principales de polimerizaci\u00f3n: natural y sint\u00e9tica. Sin embargo, esta no es la \u00fanica forma de clasificar este tipo de reacci\u00f3n qu\u00edmica. Tanto los pol\u00edmeros naturales como los sint\u00e9ticos pueden ser el resultado de la polimerizaci\u00f3n por condensaci\u00f3n o la polimerizaci\u00f3n por adici\u00f3n. Condensaci\u00f3n La polimerizaci\u00f3n por condensaci\u00f3n fue el primer tipo descubierto en 1909 por Leo Hendrik Baekeland, un qu\u00edmico belga. El invent\u00f3 la baquelita, el primer pol\u00edmero sint\u00e9tico de condensaci\u00f3n: una resina sint\u00e9tica formada a partir de la polimerizaci\u00f3n del fenol con metanal. Los pol\u00edmeros de condensaci\u00f3n se forman en etapas. Es un proceso lento, ya que la uni\u00f3n de los mon\u00f3meros ocurre individualmente, de mol\u00e9cula en mol\u00e9cula, hasta llegar a un pol\u00edmero. La principal caracter\u00edstica de este proceso es que, durante la reacci\u00f3n qu\u00edmica, se descarta una de las mol\u00e9culas de reacci\u00f3n, no estando presente en el pol\u00edmero final. Por lo tanto, sus resultados tambi\u00e9n se pueden llamar pol\u00edmeros de eliminaci\u00f3n. Adem\u00e1s de la propia baquelita, otros pol\u00edmeros de condensaci\u00f3n que utilizamos son: poli\u00e9ster: utilizado en ropa, botellas, tapicer\u00eda, instrumentos musicales, etc; poliamida (nylon): presente en cepillos de dientes, tornillos, ropa, etc; silicona: se utiliza en implantes, art\u00edculos para el hogar, cosm\u00e9ticos, moldes, etc. Reestructuraci\u00f3n Investigando este tema, se puede encontrar el t\u00e9rmino \u00abpol\u00edmeros de reestructuraci\u00f3n\u00bb. Este tipo de compuesto es el resultado de la polimerizaci\u00f3n por reestructuraci\u00f3n, un tipo de reacci\u00f3n de condensaci\u00f3n diferenciada. El poliuretano es uno de los pol\u00edmeros resultantes de \u00e9l. Adici\u00f3n La polimerizaci\u00f3n por adici\u00f3n, a su vez, ocurre a trav\u00e9s de la reacci\u00f3n en cadena, en la que debe haber la ruptura de los enlaces pi de los mon\u00f3meros. Cuando esto sucede, aparece una valencia libre de \u00e1tomos de carbono en cada mol\u00e9cula. Con esto, estas mol\u00e9culas pueden unirse entre s\u00ed, formando un pol\u00edmero. B\u00e1sicamente, hay tres procesos principales: iniciaci\u00f3n, propagaci\u00f3n y terminaci\u00f3n. Algunos ejemplos de pol\u00edmeros de adici\u00f3n que conocemos son: polietileno: utilizado en pa\u00f1ales, biberones, envases, etc; polipropileno: utilizado en sillas de pl\u00e1stico, embalajes, telas, cajas, etc; PVC: presente en cables, zapatos, tuber\u00edas, cables, productos m\u00e9dico-hospitalarios, etc.\u00a0 Grado de polimerizaci\u00f3n Otro t\u00e9rmino recurrente cuando hablamos de polimerizaci\u00f3n es el grado de polimerizaci\u00f3n. Este es un concepto simple, que representa la cantidad de meros que componen un pol\u00edmero. Sin embargo, es muy importante para esta industria. El an\u00e1lisis del grado de polimerizaci\u00f3n de un pol\u00edmero determina varios factores fundamentales sobre el compuesto estudiado. El valor de un grado de polimerizaci\u00f3n puede variar dependiendo de la masa molar y la polidispersi\u00f3n de un compuesto polim\u00e9rico. \u00a1Sigue aprendiendo de Polyexcel! \u00bfTe ha gustado saber un poco m\u00e1s sobre el universo de los pol\u00edmeros? \u00a1As\u00ed que disfruta de la visita y sigue aprendiendo del contenido que publicamos aqu\u00ed, en el blog de Polyexcel! Hay varios temas para que descubras a\u00fan m\u00e1s sobre estos compuestos tan importantes para nuestra vida diaria. \u00a1Polyexcel produce compuestos polim\u00e9ricos de calidad para que aproveches al m\u00e1ximo su bienestar! Si quieres saber m\u00e1s sobre lo que hacemos, ponte en contacto con nosotros. \u00a1Ser\u00e1 un placer presentarle nuestros productos!<\/p>\n","protected":false},"author":1,"featured_media":10076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-10075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-industria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel\" \/>\n<meta property=\"og:description\" content=\"Hay varios procesos que suceden a nuestro alrededor, pero ni siquiera podemos imaginar. \u00bfHas o\u00eddo hablar de la polimerizaci\u00f3n, por ejemplo? Esta reacci\u00f3n qu\u00edmica es la responsable de crear muchos de los objetos, materiales y compuestos con los que interactuamos en la vida diaria. Entonces, \u00bfqu\u00e9 es la polimerizaci\u00f3n y qu\u00e9 produce de tan importante? Si esa es tu pregunta, \u00a1est\u00e1s en el lugar correcto! En el siguiente contenido exclusivo, Polyexcel explicar\u00e1 todo sobre esta reacci\u00f3n y lo importante que es para la humanidad. \u00a1Sigue leyendo! \u00bfQu\u00e9 es la polimerizaci\u00f3n? En otro contenido que ya hemos tra\u00eddo a nuestro blog, explicamos en profundidad qu\u00e9 son los pol\u00edmeros. Simplemente, son macromol\u00e9culas formadas a partir de mol\u00e9culas peque\u00f1as, que llamamos mon\u00f3meros. De ah\u00ed viene el nombre de los pol\u00edmeros: \u00abpoli\u00bb significa \u00abmuchos\u00bb, mientras que \u00abmeros\u00bb significa \u00abpartes\u00bb. Sin embargo, estas partes dependen de un proceso para unirse en una sola cosa. Esta es la reacci\u00f3n de polimerizaci\u00f3n, que forma las macromol\u00e9culas que llamamos pol\u00edmeros de la uni\u00f3n de los mon\u00f3meros. Este proceso es m\u00e1s com\u00fan de lo que piensas. Todo el tiempo y en todas partes, hay mol\u00e9culas que pasan a trav\u00e9s de \u00e9l. Esto se debe a que la polimerizaci\u00f3n es una reacci\u00f3n natural, y ejemplos de esto son el l\u00e1tex, la celulosa y el almid\u00f3n. Adem\u00e1s, existe una polimerizaci\u00f3n sint\u00e9tica que, a su vez, forma pol\u00edmeros sint\u00e9ticos. Los compuestos resultantes de este proceso en el laboratorio tambi\u00e9n son bien conocidos por nosotros. Ejemplos de esto son el PVC, el polietileno y el poli\u00e9ster.\u00a0 Tipos de polimerizaci\u00f3n Como explicamos anteriormente, hay dos tipos principales de polimerizaci\u00f3n: natural y sint\u00e9tica. Sin embargo, esta no es la \u00fanica forma de clasificar este tipo de reacci\u00f3n qu\u00edmica. Tanto los pol\u00edmeros naturales como los sint\u00e9ticos pueden ser el resultado de la polimerizaci\u00f3n por condensaci\u00f3n o la polimerizaci\u00f3n por adici\u00f3n. Condensaci\u00f3n La polimerizaci\u00f3n por condensaci\u00f3n fue el primer tipo descubierto en 1909 por Leo Hendrik Baekeland, un qu\u00edmico belga. El invent\u00f3 la baquelita, el primer pol\u00edmero sint\u00e9tico de condensaci\u00f3n: una resina sint\u00e9tica formada a partir de la polimerizaci\u00f3n del fenol con metanal. Los pol\u00edmeros de condensaci\u00f3n se forman en etapas. Es un proceso lento, ya que la uni\u00f3n de los mon\u00f3meros ocurre individualmente, de mol\u00e9cula en mol\u00e9cula, hasta llegar a un pol\u00edmero. La principal caracter\u00edstica de este proceso es que, durante la reacci\u00f3n qu\u00edmica, se descarta una de las mol\u00e9culas de reacci\u00f3n, no estando presente en el pol\u00edmero final. Por lo tanto, sus resultados tambi\u00e9n se pueden llamar pol\u00edmeros de eliminaci\u00f3n. Adem\u00e1s de la propia baquelita, otros pol\u00edmeros de condensaci\u00f3n que utilizamos son: poli\u00e9ster: utilizado en ropa, botellas, tapicer\u00eda, instrumentos musicales, etc; poliamida (nylon): presente en cepillos de dientes, tornillos, ropa, etc; silicona: se utiliza en implantes, art\u00edculos para el hogar, cosm\u00e9ticos, moldes, etc. Reestructuraci\u00f3n Investigando este tema, se puede encontrar el t\u00e9rmino \u00abpol\u00edmeros de reestructuraci\u00f3n\u00bb. Este tipo de compuesto es el resultado de la polimerizaci\u00f3n por reestructuraci\u00f3n, un tipo de reacci\u00f3n de condensaci\u00f3n diferenciada. El poliuretano es uno de los pol\u00edmeros resultantes de \u00e9l. Adici\u00f3n La polimerizaci\u00f3n por adici\u00f3n, a su vez, ocurre a trav\u00e9s de la reacci\u00f3n en cadena, en la que debe haber la ruptura de los enlaces pi de los mon\u00f3meros. Cuando esto sucede, aparece una valencia libre de \u00e1tomos de carbono en cada mol\u00e9cula. Con esto, estas mol\u00e9culas pueden unirse entre s\u00ed, formando un pol\u00edmero. B\u00e1sicamente, hay tres procesos principales: iniciaci\u00f3n, propagaci\u00f3n y terminaci\u00f3n. Algunos ejemplos de pol\u00edmeros de adici\u00f3n que conocemos son: polietileno: utilizado en pa\u00f1ales, biberones, envases, etc; polipropileno: utilizado en sillas de pl\u00e1stico, embalajes, telas, cajas, etc; PVC: presente en cables, zapatos, tuber\u00edas, cables, productos m\u00e9dico-hospitalarios, etc.\u00a0 Grado de polimerizaci\u00f3n Otro t\u00e9rmino recurrente cuando hablamos de polimerizaci\u00f3n es el grado de polimerizaci\u00f3n. Este es un concepto simple, que representa la cantidad de meros que componen un pol\u00edmero. Sin embargo, es muy importante para esta industria. El an\u00e1lisis del grado de polimerizaci\u00f3n de un pol\u00edmero determina varios factores fundamentales sobre el compuesto estudiado. El valor de un grado de polimerizaci\u00f3n puede variar dependiendo de la masa molar y la polidispersi\u00f3n de un compuesto polim\u00e9rico. \u00a1Sigue aprendiendo de Polyexcel! \u00bfTe ha gustado saber un poco m\u00e1s sobre el universo de los pol\u00edmeros? \u00a1As\u00ed que disfruta de la visita y sigue aprendiendo del contenido que publicamos aqu\u00ed, en el blog de Polyexcel! Hay varios temas para que descubras a\u00fan m\u00e1s sobre estos compuestos tan importantes para nuestra vida diaria. \u00a1Polyexcel produce compuestos polim\u00e9ricos de calidad para que aproveches al m\u00e1ximo su bienestar! Si quieres saber m\u00e1s sobre lo que hacemos, ponte en contacto con nosotros. \u00a1Ser\u00e1 un placer presentarle nuestros productos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/\" \/>\n<meta property=\"og:site_name\" content=\"Polyexcel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polyexcel\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T12:59:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-01T13:03:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Polyexcel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polyexcel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/\"},\"author\":{\"name\":\"Polyexcel\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/person\\\/396d0bb8ac4e1fd019967024775dc699\"},\"headline\":\"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental!\",\"datePublished\":\"2022-03-31T12:59:50+00:00\",\"dateModified\":\"2022-04-01T13:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/\"},\"wordCount\":894,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/polimerizacao.jpg\",\"articleSection\":[\"Industria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/\",\"name\":\"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/polimerizacao.jpg\",\"datePublished\":\"2022-03-31T12:59:50+00:00\",\"dateModified\":\"2022-04-01T13:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/polimerizacao.jpg\",\"contentUrl\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/polimerizacao.jpg\",\"width\":1920,\"height\":400,\"caption\":\"polimerizaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"comienzo\",\"item\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\",\"name\":\"Polyexcel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\",\"name\":\"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Polyexcel-Assinado-16x9SQ.png\",\"contentUrl\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Polyexcel-Assinado-16x9SQ.png\",\"width\":1920,\"height\":1080,\"caption\":\"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda\"},\"image\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/polyexcel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/polyexcel\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/polyexcel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/person\\\/396d0bb8ac4e1fd019967024775dc699\",\"name\":\"Polyexcel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"caption\":\"Polyexcel\"},\"sameAs\":[\"admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel","og_description":"Hay varios procesos que suceden a nuestro alrededor, pero ni siquiera podemos imaginar. \u00bfHas o\u00eddo hablar de la polimerizaci\u00f3n, por ejemplo? Esta reacci\u00f3n qu\u00edmica es la responsable de crear muchos de los objetos, materiales y compuestos con los que interactuamos en la vida diaria. Entonces, \u00bfqu\u00e9 es la polimerizaci\u00f3n y qu\u00e9 produce de tan importante? Si esa es tu pregunta, \u00a1est\u00e1s en el lugar correcto! En el siguiente contenido exclusivo, Polyexcel explicar\u00e1 todo sobre esta reacci\u00f3n y lo importante que es para la humanidad. \u00a1Sigue leyendo! \u00bfQu\u00e9 es la polimerizaci\u00f3n? En otro contenido que ya hemos tra\u00eddo a nuestro blog, explicamos en profundidad qu\u00e9 son los pol\u00edmeros. Simplemente, son macromol\u00e9culas formadas a partir de mol\u00e9culas peque\u00f1as, que llamamos mon\u00f3meros. De ah\u00ed viene el nombre de los pol\u00edmeros: \u00abpoli\u00bb significa \u00abmuchos\u00bb, mientras que \u00abmeros\u00bb significa \u00abpartes\u00bb. Sin embargo, estas partes dependen de un proceso para unirse en una sola cosa. Esta es la reacci\u00f3n de polimerizaci\u00f3n, que forma las macromol\u00e9culas que llamamos pol\u00edmeros de la uni\u00f3n de los mon\u00f3meros. Este proceso es m\u00e1s com\u00fan de lo que piensas. Todo el tiempo y en todas partes, hay mol\u00e9culas que pasan a trav\u00e9s de \u00e9l. Esto se debe a que la polimerizaci\u00f3n es una reacci\u00f3n natural, y ejemplos de esto son el l\u00e1tex, la celulosa y el almid\u00f3n. Adem\u00e1s, existe una polimerizaci\u00f3n sint\u00e9tica que, a su vez, forma pol\u00edmeros sint\u00e9ticos. Los compuestos resultantes de este proceso en el laboratorio tambi\u00e9n son bien conocidos por nosotros. Ejemplos de esto son el PVC, el polietileno y el poli\u00e9ster.\u00a0 Tipos de polimerizaci\u00f3n Como explicamos anteriormente, hay dos tipos principales de polimerizaci\u00f3n: natural y sint\u00e9tica. Sin embargo, esta no es la \u00fanica forma de clasificar este tipo de reacci\u00f3n qu\u00edmica. Tanto los pol\u00edmeros naturales como los sint\u00e9ticos pueden ser el resultado de la polimerizaci\u00f3n por condensaci\u00f3n o la polimerizaci\u00f3n por adici\u00f3n. Condensaci\u00f3n La polimerizaci\u00f3n por condensaci\u00f3n fue el primer tipo descubierto en 1909 por Leo Hendrik Baekeland, un qu\u00edmico belga. El invent\u00f3 la baquelita, el primer pol\u00edmero sint\u00e9tico de condensaci\u00f3n: una resina sint\u00e9tica formada a partir de la polimerizaci\u00f3n del fenol con metanal. Los pol\u00edmeros de condensaci\u00f3n se forman en etapas. Es un proceso lento, ya que la uni\u00f3n de los mon\u00f3meros ocurre individualmente, de mol\u00e9cula en mol\u00e9cula, hasta llegar a un pol\u00edmero. La principal caracter\u00edstica de este proceso es que, durante la reacci\u00f3n qu\u00edmica, se descarta una de las mol\u00e9culas de reacci\u00f3n, no estando presente en el pol\u00edmero final. Por lo tanto, sus resultados tambi\u00e9n se pueden llamar pol\u00edmeros de eliminaci\u00f3n. Adem\u00e1s de la propia baquelita, otros pol\u00edmeros de condensaci\u00f3n que utilizamos son: poli\u00e9ster: utilizado en ropa, botellas, tapicer\u00eda, instrumentos musicales, etc; poliamida (nylon): presente en cepillos de dientes, tornillos, ropa, etc; silicona: se utiliza en implantes, art\u00edculos para el hogar, cosm\u00e9ticos, moldes, etc. Reestructuraci\u00f3n Investigando este tema, se puede encontrar el t\u00e9rmino \u00abpol\u00edmeros de reestructuraci\u00f3n\u00bb. Este tipo de compuesto es el resultado de la polimerizaci\u00f3n por reestructuraci\u00f3n, un tipo de reacci\u00f3n de condensaci\u00f3n diferenciada. El poliuretano es uno de los pol\u00edmeros resultantes de \u00e9l. Adici\u00f3n La polimerizaci\u00f3n por adici\u00f3n, a su vez, ocurre a trav\u00e9s de la reacci\u00f3n en cadena, en la que debe haber la ruptura de los enlaces pi de los mon\u00f3meros. Cuando esto sucede, aparece una valencia libre de \u00e1tomos de carbono en cada mol\u00e9cula. Con esto, estas mol\u00e9culas pueden unirse entre s\u00ed, formando un pol\u00edmero. B\u00e1sicamente, hay tres procesos principales: iniciaci\u00f3n, propagaci\u00f3n y terminaci\u00f3n. Algunos ejemplos de pol\u00edmeros de adici\u00f3n que conocemos son: polietileno: utilizado en pa\u00f1ales, biberones, envases, etc; polipropileno: utilizado en sillas de pl\u00e1stico, embalajes, telas, cajas, etc; PVC: presente en cables, zapatos, tuber\u00edas, cables, productos m\u00e9dico-hospitalarios, etc.\u00a0 Grado de polimerizaci\u00f3n Otro t\u00e9rmino recurrente cuando hablamos de polimerizaci\u00f3n es el grado de polimerizaci\u00f3n. Este es un concepto simple, que representa la cantidad de meros que componen un pol\u00edmero. Sin embargo, es muy importante para esta industria. El an\u00e1lisis del grado de polimerizaci\u00f3n de un pol\u00edmero determina varios factores fundamentales sobre el compuesto estudiado. El valor de un grado de polimerizaci\u00f3n puede variar dependiendo de la masa molar y la polidispersi\u00f3n de un compuesto polim\u00e9rico. \u00a1Sigue aprendiendo de Polyexcel! \u00bfTe ha gustado saber un poco m\u00e1s sobre el universo de los pol\u00edmeros? \u00a1As\u00ed que disfruta de la visita y sigue aprendiendo del contenido que publicamos aqu\u00ed, en el blog de Polyexcel! Hay varios temas para que descubras a\u00fan m\u00e1s sobre estos compuestos tan importantes para nuestra vida diaria. \u00a1Polyexcel produce compuestos polim\u00e9ricos de calidad para que aproveches al m\u00e1ximo su bienestar! Si quieres saber m\u00e1s sobre lo que hacemos, ponte en contacto con nosotros. \u00a1Ser\u00e1 un placer presentarle nuestros productos!","og_url":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/","og_site_name":"Polyexcel","article_publisher":"https:\/\/www.facebook.com\/polyexcel\/","article_published_time":"2022-03-31T12:59:50+00:00","article_modified_time":"2022-04-01T13:03:49+00:00","og_image":[{"width":1920,"height":400,"url":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg","type":"image\/jpeg"}],"author":"Polyexcel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Polyexcel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#article","isPartOf":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/"},"author":{"name":"Polyexcel","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/person\/396d0bb8ac4e1fd019967024775dc699"},"headline":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental!","datePublished":"2022-03-31T12:59:50+00:00","dateModified":"2022-04-01T13:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/"},"wordCount":894,"commentCount":0,"publisher":{"@id":"https:\/\/polyexcel.com.br\/es\/#organization"},"image":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#primaryimage"},"thumbnailUrl":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg","articleSection":["Industria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/","url":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/","name":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental! | Polyexcel","isPartOf":{"@id":"https:\/\/polyexcel.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#primaryimage"},"image":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#primaryimage"},"thumbnailUrl":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg","datePublished":"2022-03-31T12:59:50+00:00","dateModified":"2022-04-01T13:03:49+00:00","breadcrumb":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#primaryimage","url":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg","contentUrl":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2022\/04\/polimerizacao.jpg","width":1920,"height":400,"caption":"polimerizaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sabes-que-es-la-polimerizacion-conoce-este-proceso-fundamental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"comienzo","item":"https:\/\/polyexcel.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfSabes qu\u00e9 es la polimerizaci\u00f3n? \u00a1Conoce este proceso fundamental!"}]},{"@type":"WebSite","@id":"https:\/\/polyexcel.com.br\/es\/#website","url":"https:\/\/polyexcel.com.br\/es\/","name":"Polyexcel","description":"","publisher":{"@id":"https:\/\/polyexcel.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polyexcel.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/polyexcel.com.br\/es\/#organization","name":"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda","url":"https:\/\/polyexcel.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2023\/01\/Logo-Polyexcel-Assinado-16x9SQ.png","contentUrl":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2023\/01\/Logo-Polyexcel-Assinado-16x9SQ.png","width":1920,"height":1080,"caption":"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda"},"image":{"@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/polyexcel\/","https:\/\/www.instagram.com\/polyexcel\/","https:\/\/www.linkedin.com\/company\/polyexcel\/"]},{"@type":"Person","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/person\/396d0bb8ac4e1fd019967024775dc699","name":"Polyexcel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","caption":"Polyexcel"},"sameAs":["admin"]}]}},"_links":{"self":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts\/10075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/comments?post=10075"}],"version-history":[{"count":0,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts\/10075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/media\/10076"}],"wp:attachment":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/media?parent=10075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/categories?post=10075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/tags?post=10075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}