{"id":7438,"date":"2020-11-25T18:06:46","date_gmt":"2020-11-25T21:06:46","guid":{"rendered":"https:\/\/polyexcel.com.br\/?p=7438"},"modified":"2020-12-14T10:36:22","modified_gmt":"2020-12-14T13:36:22","slug":"sepa-que-es-aislamiento-termico-y-sus-principales-tipos","status":"publish","type":"post","link":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/","title":{"rendered":"Sepa qu\u00e9 es aislamiento t\u00e9rmico y sus principales tipos"},"content":{"rendered":"<p>Ampliamente utilizado en la construcci\u00f3n civil, el <strong>aislamiento t\u00e9rmico<\/strong> es un tipo de material o estructura que dificulta la disipaci\u00f3n del calor debido a su resistencia t\u00e9rmica. Para que eso ocurra, ello establece una barrera en el pasaje de calor entre dos medios que naturalmente igualar\u00edan sus temperaturas.<\/p>\n<p>En general, no existen materiales que a\u00edslen perfectamente y eviten por completo el intercambio de calor. Sin embargo, hay aislantes que retrasan mucho este intercambio, siendo considerados los mejores <strong>en aislamiento t\u00e9rmico industrial<\/strong> y residencial. Podemos mencionar la espuma de poliestireno, corcho, vidrio y lana de vidrio.<\/p>\n<p>Existen varios materiales s\u00f3lidos que pueden ser buenos aislantes el\u00e9ctricos, lo que definir\u00e1 esta es la temperatura, la utilidad dada y el lugar de instalaci\u00f3n. Siga el blog de Polyexcel para obtener m\u00e1s informaci\u00f3n sobre <strong>qu\u00e9 son los aislantes t\u00e9rmicos<\/strong>.<\/p>\n<h2>Tipos de aislamiento t\u00e9rmico<\/h2>\n<p>Existen varios materiales que se pueden utilizar para hacer el aislamiento t\u00e9rmico y el\u00e9ctrico. Aunque cada estructura genere calor, los tipos y <strong>estrategias de aislamiento t\u00e9rmico<\/strong> ayudan a aumentar la protecci\u00f3n de conductores, evitando posibles accidentes. Vea a continuaci\u00f3n los principales ejemplos de ellos.<\/p>\n<h3>Corcho<\/h3>\n<p>El corcho es uno de los aislantes m\u00e1s antiguos. Generalmente se utiliza en forma de aglomerados, formando paneles. La mayor ventaja de ese tipo de aislamiento t\u00e9rmico es la inercia t\u00e9rmica que presenta.<\/p>\n<h3>Lana de roca<\/h3>\n<p>Imputrescible e incombustible, la lana de roca se diferencia de otros aislantes en que es resistente al fuego, con un punto de fusi\u00f3n por encima de los 1.200\u00baC. Sus principales aplicaciones son el aislamiento de techos, fachadas ventiladas, tabiques previos y mucho m\u00e1s.<\/p>\n<p>Esta estructura se comercializa en paneles r\u00edgidos o semirr\u00edgidos, fieltros, mantas, aglomerados con resinas y coquinas para aislar tuber\u00edas de secci\u00f3n circular. Recuerda que tambi\u00e9n es una excelente opci\u00f3n para el <strong>aislamiento t\u00e9rmico de edificios<\/strong> y tambi\u00e9n ac\u00fastico, sea en techos y paredes interiores.<\/p>\n<h3>Lana de vidrio<\/h3>\n<p>Similar a la lana de roca, la lana de vidrio tiene s\u00edlice y sodio (arena y vidrio), que se funden a alta temperatura y se centrifugan (1.800\u00baC). Esta uni\u00f3n forma hilos finos, que luego se agregan con resina sint\u00e9tica.<\/p>\n<p>Al igual que los <strong>materiales aislantes t\u00e9rmicos<\/strong> anteriores, esta opci\u00f3n se encuentra en forma de manta, paneles aglomerados y coquinhas aislantes de tuber\u00edas. Adem\u00e1s, puede tener versiones con mayor densidad, repelentes al agua e higrosc\u00f3picas.<\/p>\n<h3>Poliestireno expandido (EPS)<\/h3>\n<p>Entre los principales ejemplos de materiales conductores y aislantes t\u00e9rmicos se encuentra el poliestireno expandido, un material derivado del petr\u00f3leo y el gas natural. A trav\u00e9s de \u00e9l, se obtiene el pol\u00edmero pl\u00e1stico de estireno en forma de gr\u00e1nulos.<\/p>\n<p>Debido a su combustibilidad, se a\u00f1aden retardadores de llama a la composici\u00f3n, haciendo del poliestireno un compuesto poco inflamable. Pero no se detiene ah\u00ed, ya que en estado l\u00edquido tiene una alta resistencia a la absorci\u00f3n de agua.<\/p>\n<h3>Espuma de polietileno<\/h3>\n<p>La espuma de polipropileno es repelente al agua, econ\u00f3mica y tiene un rendimiento t\u00e9rmico medio. Acabado en blanco o cercano al aluminio, tiene un coeficiente de conductividad t\u00e9rmica entre 0.036 y 0.046 W \/ m\u00baC. Adem\u00e1s, se puede vender en forma de l\u00e1minas, bloques y tubos.<\/p>\n<h3>Espuma de polipropileno<\/h3>\n<p>Aunque similar a la espuma anterior, la versi\u00f3n de polipropileno ofrece caracter\u00edsticas qu\u00edmicas de mayor resistencia t\u00e9rmica, siendo \u00fatil en el aislamiento de tubos de acero en procesos industriales. Su comercializaci\u00f3n se presenta de la misma forma que el polietileno.<\/p>\n<h2>Polyexcel: excelencia en compuestos polim\u00e9ricos<\/h2>\n<p><a href=\"https:\/\/polyexcel.com.br\/\">Polyexcel<\/a>, considerado uno de los mayores productores de compuestos polim\u00e9ricos para alambres y cables de energ\u00eda y telecomunicaciones, siempre est\u00e1 buscando productos de alta calidad. Para ello, cuenta con un laboratorio lleno de equipos \u00fanicos en el territorio nacional.<\/p>\n<p>Fundada en 2011 con el objetivo de producir compuestos XLPE, uno de los buques insignia de la compa\u00f1\u00eda, Polyexcel ha ampliado su cat\u00e1logo con varios aislantes el\u00e9ctricos de alto rendimiento. Un ejemplo de ello es el <a href=\"https:\/\/polyexcel.com.br\/hffr\/\">HFFR<\/a>, un compuesto que adem\u00e1s de retardante de llama, no contiene hal\u00f3genos y tiene baja emisi\u00f3n de humos.<\/p>\n<h2>\u00a1Invierta en compuestos Polyexcel!<\/h2>\n<p>\u00bfQuieres saber m\u00e1s sobre los aislantes el\u00e9ctricos Polyexcel? Acceda a nuestro sitio web y complete el formulario en la parte inferior de la p\u00e1gina del compuesto para solicitar la ficha t\u00e9cnica de cada producto. Para aclarar otro tipo de dudas, env\u00edenos un mensaje a trav\u00e9s de la p\u00e1gina \u201c<a href=\"https:\/\/polyexcel.com.br\/es\/entre-en-contacto\/\">cont\u00e1ctenos<\/a>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampliamente utilizado en la construcci\u00f3n civil, el aislamiento t\u00e9rmico es un tipo de material o estructura que dificulta la disipaci\u00f3n del calor debido a su resistencia t\u00e9rmica. Para que eso ocurra, ello establece una barrera en el pasaje de calor entre dos medios que naturalmente igualar\u00edan sus temperaturas. En general, no existen materiales que a\u00edslen perfectamente y eviten por completo el intercambio de calor. Sin embargo, hay aislantes que retrasan mucho este intercambio, siendo considerados los mejores en aislamiento t\u00e9rmico industrial y residencial. Podemos mencionar la espuma de poliestireno, corcho, vidrio y lana de vidrio. Existen varios materiales s\u00f3lidos que pueden ser buenos aislantes el\u00e9ctricos, lo que definir\u00e1 esta es la temperatura, la utilidad dada y el lugar de instalaci\u00f3n. Siga el blog de Polyexcel para obtener m\u00e1s informaci\u00f3n sobre qu\u00e9 son los aislantes t\u00e9rmicos. Tipos de aislamiento t\u00e9rmico Existen varios materiales que se pueden utilizar para hacer el aislamiento t\u00e9rmico y el\u00e9ctrico. Aunque cada estructura genere calor, los tipos y estrategias de aislamiento t\u00e9rmico ayudan a aumentar la protecci\u00f3n de conductores, evitando posibles accidentes. Vea a continuaci\u00f3n los principales ejemplos de ellos. Corcho El corcho es uno de los aislantes m\u00e1s antiguos. Generalmente se utiliza en forma de aglomerados, formando paneles. La mayor ventaja de ese tipo de aislamiento t\u00e9rmico es la inercia t\u00e9rmica que presenta. Lana de roca Imputrescible e incombustible, la lana de roca se diferencia de otros aislantes en que es resistente al fuego, con un punto de fusi\u00f3n por encima de los 1.200\u00baC. Sus principales aplicaciones son el aislamiento de techos, fachadas ventiladas, tabiques previos y mucho m\u00e1s. Esta estructura se comercializa en paneles r\u00edgidos o semirr\u00edgidos, fieltros, mantas, aglomerados con resinas y coquinas para aislar tuber\u00edas de secci\u00f3n circular. Recuerda que tambi\u00e9n es una excelente opci\u00f3n para el aislamiento t\u00e9rmico de edificios y tambi\u00e9n ac\u00fastico, sea en techos y paredes interiores. Lana de vidrio Similar a la lana de roca, la lana de vidrio tiene s\u00edlice y sodio (arena y vidrio), que se funden a alta temperatura y se centrifugan (1.800\u00baC). Esta uni\u00f3n forma hilos finos, que luego se agregan con resina sint\u00e9tica. Al igual que los materiales aislantes t\u00e9rmicos anteriores, esta opci\u00f3n se encuentra en forma de manta, paneles aglomerados y coquinhas aislantes de tuber\u00edas. Adem\u00e1s, puede tener versiones con mayor densidad, repelentes al agua e higrosc\u00f3picas. Poliestireno expandido (EPS) Entre los principales ejemplos de materiales conductores y aislantes t\u00e9rmicos se encuentra el poliestireno expandido, un material derivado del petr\u00f3leo y el gas natural. A trav\u00e9s de \u00e9l, se obtiene el pol\u00edmero pl\u00e1stico de estireno en forma de gr\u00e1nulos. Debido a su combustibilidad, se a\u00f1aden retardadores de llama a la composici\u00f3n, haciendo del poliestireno un compuesto poco inflamable. Pero no se detiene ah\u00ed, ya que en estado l\u00edquido tiene una alta resistencia a la absorci\u00f3n de agua. Espuma de polietileno La espuma de polipropileno es repelente al agua, econ\u00f3mica y tiene un rendimiento t\u00e9rmico medio. Acabado en blanco o cercano al aluminio, tiene un coeficiente de conductividad t\u00e9rmica entre 0.036 y 0.046 W \/ m\u00baC. Adem\u00e1s, se puede vender en forma de l\u00e1minas, bloques y tubos. Espuma de polipropileno Aunque similar a la espuma anterior, la versi\u00f3n de polipropileno ofrece caracter\u00edsticas qu\u00edmicas de mayor resistencia t\u00e9rmica, siendo \u00fatil en el aislamiento de tubos de acero en procesos industriales. Su comercializaci\u00f3n se presenta de la misma forma que el polietileno. Polyexcel: excelencia en compuestos polim\u00e9ricos Polyexcel, considerado uno de los mayores productores de compuestos polim\u00e9ricos para alambres y cables de energ\u00eda y telecomunicaciones, siempre est\u00e1 buscando productos de alta calidad. Para ello, cuenta con un laboratorio lleno de equipos \u00fanicos en el territorio nacional. Fundada en 2011 con el objetivo de producir compuestos XLPE, uno de los buques insignia de la compa\u00f1\u00eda, Polyexcel ha ampliado su cat\u00e1logo con varios aislantes el\u00e9ctricos de alto rendimiento. Un ejemplo de ello es el HFFR, un compuesto que adem\u00e1s de retardante de llama, no contiene hal\u00f3genos y tiene baja emisi\u00f3n de humos. \u00a1Invierta en compuestos Polyexcel! \u00bfQuieres saber m\u00e1s sobre los aislantes el\u00e9ctricos Polyexcel? Acceda a nuestro sitio web y complete el formulario en la parte inferior de la p\u00e1gina del compuesto para solicitar la ficha t\u00e9cnica de cada producto. Para aclarar otro tipo de dudas, env\u00edenos un mensaje a trav\u00e9s de la p\u00e1gina \u201ccont\u00e1ctenos\u201d.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-7438","post","type-post","status-publish","format-standard","hentry","category-esp-industria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel<\/title>\n<meta name=\"description\" content=\"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel\" \/>\n<meta property=\"og:description\" content=\"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/\" \/>\n<meta property=\"og:site_name\" content=\"Polyexcel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polyexcel\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T21:06:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-14T13:36:22+00:00\" \/>\n<meta name=\"author\" content=\"Polyexcel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polyexcel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/\"},\"author\":{\"name\":\"Polyexcel\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/person\\\/396d0bb8ac4e1fd019967024775dc699\"},\"headline\":\"Sepa qu\u00e9 es aislamiento t\u00e9rmico y sus principales tipos\",\"datePublished\":\"2020-11-25T21:06:46+00:00\",\"dateModified\":\"2020-12-14T13:36:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/\"},\"wordCount\":792,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\"},\"articleSection\":[\"Industria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/\",\"name\":\"Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#website\"},\"datePublished\":\"2020-11-25T21:06:46+00:00\",\"dateModified\":\"2020-12-14T13:36:22+00:00\",\"description\":\"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/esp-industria\\\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"comienzo\",\"item\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sepa qu\u00e9 es aislamiento t\u00e9rmico y sus principales tipos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\",\"name\":\"Polyexcel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#organization\",\"name\":\"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Polyexcel-Assinado-16x9SQ.png\",\"contentUrl\":\"https:\\\/\\\/polyexcel.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo-Polyexcel-Assinado-16x9SQ.png\",\"width\":1920,\"height\":1080,\"caption\":\"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda\"},\"image\":{\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/polyexcel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/polyexcel\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/polyexcel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/polyexcel.com.br\\\/es\\\/#\\\/schema\\\/person\\\/396d0bb8ac4e1fd019967024775dc699\",\"name\":\"Polyexcel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g\",\"caption\":\"Polyexcel\"},\"sameAs\":[\"admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel","description":"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/","og_locale":"es_ES","og_type":"article","og_title":"Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel","og_description":"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!","og_url":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/","og_site_name":"Polyexcel","article_publisher":"https:\/\/www.facebook.com\/polyexcel\/","article_published_time":"2020-11-25T21:06:46+00:00","article_modified_time":"2020-12-14T13:36:22+00:00","author":"Polyexcel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Polyexcel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/#article","isPartOf":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/"},"author":{"name":"Polyexcel","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/person\/396d0bb8ac4e1fd019967024775dc699"},"headline":"Sepa qu\u00e9 es aislamiento t\u00e9rmico y sus principales tipos","datePublished":"2020-11-25T21:06:46+00:00","dateModified":"2020-12-14T13:36:22+00:00","mainEntityOfPage":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/"},"wordCount":792,"commentCount":0,"publisher":{"@id":"https:\/\/polyexcel.com.br\/es\/#organization"},"articleSection":["Industria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/","url":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/","name":"Sepa todo sobre el aislamiento t\u00e9rmico | Polyexcel","isPartOf":{"@id":"https:\/\/polyexcel.com.br\/es\/#website"},"datePublished":"2020-11-25T21:06:46+00:00","dateModified":"2020-12-14T13:36:22+00:00","description":"\u00bfSabes qu\u00e9 es el aislamiento t\u00e9rmico y para qu\u00e9 funciona? \u00a1Visite el blog de Polyexcel para descubrir c\u00f3mo funcionan estos materiales!","breadcrumb":{"@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/polyexcel.com.br\/es\/esp-industria\/sepa-que-es-aislamiento-termico-y-sus-principales-tipos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"comienzo","item":"https:\/\/polyexcel.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Sepa qu\u00e9 es aislamiento t\u00e9rmico y sus principales tipos"}]},{"@type":"WebSite","@id":"https:\/\/polyexcel.com.br\/es\/#website","url":"https:\/\/polyexcel.com.br\/es\/","name":"Polyexcel","description":"","publisher":{"@id":"https:\/\/polyexcel.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polyexcel.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/polyexcel.com.br\/es\/#organization","name":"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda","url":"https:\/\/polyexcel.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2023\/01\/Logo-Polyexcel-Assinado-16x9SQ.png","contentUrl":"https:\/\/polyexcel.com.br\/wp-content\/uploads\/2023\/01\/Logo-Polyexcel-Assinado-16x9SQ.png","width":1920,"height":1080,"caption":"Polyexcel Ind\u00fastria e Com\u00e9rcio de Compostos Polim\u00e9ricos Ltda"},"image":{"@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/polyexcel\/","https:\/\/www.instagram.com\/polyexcel\/","https:\/\/www.linkedin.com\/company\/polyexcel\/"]},{"@type":"Person","@id":"https:\/\/polyexcel.com.br\/es\/#\/schema\/person\/396d0bb8ac4e1fd019967024775dc699","name":"Polyexcel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c15d9e2d98e4508dcea42f3a128071c1930332b2a049c69ebdc71d50b883bc7?s=96&d=mm&r=g","caption":"Polyexcel"},"sameAs":["admin"]}]}},"_links":{"self":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts\/7438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/comments?post=7438"}],"version-history":[{"count":0,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/posts\/7438\/revisions"}],"wp:attachment":[{"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/media?parent=7438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/categories?post=7438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polyexcel.com.br\/es\/wp-json\/wp\/v2\/tags?post=7438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}